{"id":52808,"date":"2022-12-08T15:57:30","date_gmt":"2022-12-08T15:57:30","guid":{"rendered":"https:\/\/argentinareloaded.com\/?p=52808"},"modified":"2025-04-28T16:51:22","modified_gmt":"2025-04-28T16:51:22","slug":"sao-paulo-brazil","status":"publish","type":"post","link":"https:\/\/argentinareloaded.com\/eng\/sao-paulo-brazil\/","title":{"rendered":"SAO PAULO, Brazil"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top:0px;--awb-padding-right:0px;--awb-padding-bottom:0px;--awb-padding-left:0px;--awb-margin-top:0px;--awb-margin-bottom:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1144px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-blog-shortcode fusion-blog-shortcode-1 fusion-blog-archive fusion-blog-layout-grid-wrapper fusion-blog-no fusion-blog-layout-left\"><style type=\"text\/css\">.fusion-blog-shortcode-1 .fusion-blog-layout-grid .fusion-post-grid{padding:5px;}.fusion-blog-shortcode-1 .fusion-posts-container{margin-left: -5px !important; margin-right:-5px !important;}<\/style><div class=\"fusion-posts-container fusion-posts-container-no fusion-no-meta-info fusion-blog-rollover fusion-blog-layout-grid fusion-blog-layout-grid-6 isotope\" data-pages=\"0\" data-grid-col-space=\"10\" style=\"margin: -5px -5px 0;min-height:500px;\"><article id=\"blog-1-post-52904\" class=\"fusion-post-grid post-52904 post type-post status-publish format-standard has-post-thumbnail hentry category-sao-paulo category-vaxjo\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/logo-altar-uco-cuadrado-ok.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/logo-altar-uco-cuadrado-ok-200x200.jpg 200w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/logo-altar-uco-cuadrado-ok-400x400.jpg 400w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/logo-altar-uco-cuadrado-ok-600x600.jpg 600w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/logo-altar-uco-cuadrado-ok-800x800.jpg 800w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/logo-altar-uco-cuadrado-ok.jpg 900w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1000px) 175px, (min-width: 928px) 210px, (min-width: 856px) 263px, (min-width: 784px) 350px, (min-width: 712px) 525px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/argentinareloaded.com\/eng\/altar-uco-2\/\" aria-label=\"Altar Uco\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px; display:none;\"><div class=\"fusion-post-content post-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-52909\" class=\"fusion-post-grid post-52909 post type-post status-publish format-standard has-post-thumbnail hentry category-sao-paulo\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-CANOPUS-CUADRADO-OK.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-CANOPUS-CUADRADO-OK-200x200.jpg 200w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-CANOPUS-CUADRADO-OK-400x400.jpg 400w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-CANOPUS-CUADRADO-OK-600x600.jpg 600w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-CANOPUS-CUADRADO-OK-800x800.jpg 800w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-CANOPUS-CUADRADO-OK.jpg 900w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1000px) 175px, (min-width: 928px) 210px, (min-width: 856px) 263px, (min-width: 784px) 350px, (min-width: 712px) 525px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/argentinareloaded.com\/eng\/canopus-3\/\" aria-label=\"Canopus\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px; display:none;\"><div class=\"fusion-post-content post-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-51655\" class=\"fusion-post-grid post-51655 post type-post status-publish format-standard has-post-thumbnail hentry category-beaune category-sao-paulo category-vaxjo\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-cara-sur-cuadrado-web-ok.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-cara-sur-cuadrado-web-ok-200x200.png 200w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-cara-sur-cuadrado-web-ok-400x400.png 400w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-cara-sur-cuadrado-web-ok-600x600.png 600w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-cara-sur-cuadrado-web-ok-800x800.png 800w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-cara-sur-cuadrado-web-ok.png 900w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1000px) 175px, (min-width: 928px) 210px, (min-width: 856px) 263px, (min-width: 784px) 350px, (min-width: 712px) 525px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/argentinareloaded.com\/eng\/cara-sur\/\" aria-label=\"Cara Sur\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px; display:none;\"><div class=\"fusion-post-content post-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-52612\" class=\"fusion-post-grid post-52612 post type-post status-publish format-standard has-post-thumbnail hentry category-oslo-ok category-sao-paulo category-trondheim\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/LOGO-EL-BAYEH-OK.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/LOGO-EL-BAYEH-OK-200x200.jpg 200w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/LOGO-EL-BAYEH-OK-400x400.jpg 400w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/LOGO-EL-BAYEH-OK-600x600.jpg 600w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/LOGO-EL-BAYEH-OK-800x800.jpg 800w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/LOGO-EL-BAYEH-OK.jpg 1000w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1000px) 175px, (min-width: 928px) 210px, (min-width: 856px) 263px, (min-width: 784px) 350px, (min-width: 712px) 525px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/argentinareloaded.com\/eng\/el-bayeh\/\" aria-label=\"El Bayeh\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px; display:none;\"><div class=\"fusion-post-content post-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-52830\" class=\"fusion-post-grid post-52830 post type-post status-publish format-standard has-post-thumbnail hentry category-sao-paulo\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/07\/logo-cuadrado-escala-humana-ok.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/07\/logo-cuadrado-escala-humana-ok-200x200.jpg 200w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/07\/logo-cuadrado-escala-humana-ok-400x400.jpg 400w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/07\/logo-cuadrado-escala-humana-ok-600x600.jpg 600w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/07\/logo-cuadrado-escala-humana-ok-800x800.jpg 800w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/07\/logo-cuadrado-escala-humana-ok.jpg 900w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1000px) 175px, (min-width: 928px) 210px, (min-width: 856px) 263px, (min-width: 784px) 350px, (min-width: 712px) 525px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/argentinareloaded.com\/eng\/escala-humana-3\/\" aria-label=\"Escala Humana\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px; display:none;\"><div class=\"fusion-post-content post-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-52822\" class=\"fusion-post-grid post-52822 post type-post status-publish format-standard has-post-thumbnail hentry category-sao-paulo category-vaxjo\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-finca-suarez-web-ok.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-finca-suarez-web-ok-200x200.png 200w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-finca-suarez-web-ok-400x400.png 400w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-finca-suarez-web-ok-600x600.png 600w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-finca-suarez-web-ok-800x800.png 800w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-finca-suarez-web-ok.png 900w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1000px) 175px, (min-width: 928px) 210px, (min-width: 856px) 263px, (min-width: 784px) 350px, (min-width: 712px) 525px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/argentinareloaded.com\/eng\/finca-suarez-3\/\" aria-label=\"Finca Suarez\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px; display:none;\"><div class=\"fusion-post-content post-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-52826\" class=\"fusion-post-grid post-52826 post type-post status-publish format-standard has-post-thumbnail hentry category-sao-paulo category-vaxjo\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-ZUCCARDI-CUADRADO-OK.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-ZUCCARDI-CUADRADO-OK-200x200.png 200w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-ZUCCARDI-CUADRADO-OK-400x400.png 400w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-ZUCCARDI-CUADRADO-OK-600x600.png 600w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-ZUCCARDI-CUADRADO-OK-800x800.png 800w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-ZUCCARDI-CUADRADO-OK.png 900w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1000px) 175px, (min-width: 928px) 210px, (min-width: 856px) 263px, (min-width: 784px) 350px, (min-width: 712px) 525px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/argentinareloaded.com\/eng\/zuccardi-4\/\" aria-label=\"Zuccardi\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px; display:none;\"><div class=\"fusion-post-content post-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-52888\" class=\"fusion-post-grid post-52888 post type-post status-publish format-standard has-post-thumbnail hentry category-sao-paulo\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/logo-el-enemigo-cuadrado-ok.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/logo-el-enemigo-cuadrado-ok-200x200.jpg 200w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/logo-el-enemigo-cuadrado-ok-400x400.jpg 400w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/logo-el-enemigo-cuadrado-ok-600x600.jpg 600w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/logo-el-enemigo-cuadrado-ok-800x800.jpg 800w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/logo-el-enemigo-cuadrado-ok.jpg 900w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1000px) 175px, (min-width: 928px) 210px, (min-width: 856px) 263px, (min-width: 784px) 350px, (min-width: 712px) 525px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/argentinareloaded.com\/eng\/el-enemigo-2\/\" aria-label=\"El Enemigo\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px; display:none;\"><div class=\"fusion-post-content post-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-52815\" class=\"fusion-post-grid post-52815 post type-post status-publish format-standard has-post-thumbnail hentry category-sao-paulo\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-OTRONIA-WEB-OK.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-OTRONIA-WEB-OK-200x200.jpg 200w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-OTRONIA-WEB-OK-400x400.jpg 400w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-OTRONIA-WEB-OK-600x600.jpg 600w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-OTRONIA-WEB-OK-800x800.jpg 800w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/LOGO-OTRONIA-WEB-OK.jpg 900w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1000px) 175px, (min-width: 928px) 210px, (min-width: 856px) 263px, (min-width: 784px) 350px, (min-width: 712px) 525px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/argentinareloaded.com\/eng\/otronia-2\/\" aria-label=\"Otronia\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px; display:none;\"><div class=\"fusion-post-content post-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-52858\" class=\"fusion-post-grid post-52858 post type-post status-publish format-standard has-post-thumbnail hentry category-sao-paulo\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/Michelini-i-mufatto-logo-cuadrado-web-ok.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/Michelini-i-mufatto-logo-cuadrado-web-ok-200x200.png 200w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/Michelini-i-mufatto-logo-cuadrado-web-ok-400x400.png 400w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/Michelini-i-mufatto-logo-cuadrado-web-ok-600x600.png 600w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/Michelini-i-mufatto-logo-cuadrado-web-ok-800x800.png 800w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/Michelini-i-mufatto-logo-cuadrado-web-ok.png 900w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1000px) 175px, (min-width: 928px) 210px, (min-width: 856px) 263px, (min-width: 784px) 350px, (min-width: 712px) 525px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/argentinareloaded.com\/eng\/michelini-i-mufatto-4\/\" aria-label=\"Michelini i Mufatto\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px; display:none;\"><div class=\"fusion-post-content post-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-52949\" class=\"fusion-post-grid post-52949 post type-post status-publish format-standard has-post-thumbnail hentry category-sao-paulo\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/MUNDO-REVES-CUADRADO-OK.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/MUNDO-REVES-CUADRADO-OK-200x200.png 200w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/MUNDO-REVES-CUADRADO-OK-400x400.png 400w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/MUNDO-REVES-CUADRADO-OK-600x600.png 600w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/MUNDO-REVES-CUADRADO-OK-800x800.png 800w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/MUNDO-REVES-CUADRADO-OK.png 900w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1000px) 175px, (min-width: 928px) 210px, (min-width: 856px) 263px, (min-width: 784px) 350px, (min-width: 712px) 525px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/argentinareloaded.com\/eng\/mundo-reves-3\/\" aria-label=\"Mundo Reves\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px; display:none;\"><div class=\"fusion-post-content post-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-52894\" class=\"fusion-post-grid post-52894 post type-post status-publish format-standard has-post-thumbnail hentry category-sao-paulo\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-riccitelli-cuadrado-web-ok.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-riccitelli-cuadrado-web-ok-200x200.png 200w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-riccitelli-cuadrado-web-ok-400x400.png 400w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-riccitelli-cuadrado-web-ok-600x600.png 600w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-riccitelli-cuadrado-web-ok-800x800.png 800w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/logo-riccitelli-cuadrado-web-ok.png 900w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1000px) 175px, (min-width: 928px) 210px, (min-width: 856px) 263px, (min-width: 784px) 350px, (min-width: 712px) 525px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/argentinareloaded.com\/eng\/riccitelli-wines-3\/\" aria-label=\"Riccitelli Wines\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px; display:none;\"><div class=\"fusion-post-content post-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-52828\" class=\"fusion-post-grid post-52828 post type-post status-publish format-standard has-post-thumbnail hentry category-sao-paulo\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/SUPERUCO2-CUADRADO-OK.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/SUPERUCO2-CUADRADO-OK-200x200.jpg 200w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/SUPERUCO2-CUADRADO-OK-400x400.jpg 400w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/SUPERUCO2-CUADRADO-OK-600x600.jpg 600w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/SUPERUCO2-CUADRADO-OK-800x800.jpg 800w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/SUPERUCO2-CUADRADO-OK.jpg 900w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1000px) 175px, (min-width: 928px) 210px, (min-width: 856px) 263px, (min-width: 784px) 350px, (min-width: 712px) 525px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/argentinareloaded.com\/eng\/super-uco-2\/\" aria-label=\"Super Uco\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px; display:none;\"><div class=\"fusion-post-content post-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-52896\" class=\"fusion-post-grid post-52896 post type-post status-publish format-standard has-post-thumbnail hentry category-sao-paulo\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/Susana-Balbo.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/Susana-Balbo-200x200.jpg 200w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/Susana-Balbo-400x400.jpg 400w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/Susana-Balbo-600x600.jpg 600w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/Susana-Balbo-800x800.jpg 800w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/06\/Susana-Balbo.jpg 1080w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1000px) 175px, (min-width: 928px) 210px, (min-width: 856px) 263px, (min-width: 784px) 350px, (min-width: 712px) 525px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/argentinareloaded.com\/eng\/susana-balbo-2\/\" aria-label=\"Susana Balbo\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px; display:none;\"><div class=\"fusion-post-content post-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-52820\" class=\"fusion-post-grid post-52820 post type-post status-publish format-standard has-post-thumbnail hentry category-sao-paulo\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/07\/logo-tinto-negro-cuadrado-ok-1.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/07\/logo-tinto-negro-cuadrado-ok-1-200x200.jpg 200w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/07\/logo-tinto-negro-cuadrado-ok-1-400x400.jpg 400w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/07\/logo-tinto-negro-cuadrado-ok-1-600x600.jpg 600w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/07\/logo-tinto-negro-cuadrado-ok-1-800x800.jpg 800w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/07\/logo-tinto-negro-cuadrado-ok-1.jpg 900w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1000px) 175px, (min-width: 928px) 210px, (min-width: 856px) 263px, (min-width: 784px) 350px, (min-width: 712px) 525px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/argentinareloaded.com\/eng\/las-fincas\/\" aria-label=\"Tinto Negro\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px; display:none;\"><div class=\"fusion-post-content post-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-52824\" class=\"fusion-post-grid post-52824 post type-post status-publish format-standard has-post-thumbnail hentry category-sao-paulo\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #ebeaea;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#ebeaea;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/12\/logo-valle-arriba-web-ok-cuadrado.jpg\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/12\/logo-valle-arriba-web-ok-cuadrado-200x200.jpg 200w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/12\/logo-valle-arriba-web-ok-cuadrado-400x400.jpg 400w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/12\/logo-valle-arriba-web-ok-cuadrado-600x600.jpg 600w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/12\/logo-valle-arriba-web-ok-cuadrado-800x800.jpg 800w, https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/12\/logo-valle-arriba-web-ok-cuadrado.jpg 900w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 1000px) 175px, (min-width: 928px) 210px, (min-width: 856px) 263px, (min-width: 784px) 350px, (min-width: 712px) 525px, (min-width: 640px) 712px, \" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/argentinareloaded.com\/eng\/valle-arriba-2\/\" aria-label=\"Valle Arriba\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px; display:none;\"><div class=\"fusion-post-content post-content\"><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":52444,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19],"tags":[],"class_list":["post-52808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-old"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SAO PAULO, Brazil - Argentina Reloaded<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/argentinareloaded.com\/eng\/sao-paulo-brazil\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SAO PAULO, Brazil - Argentina Reloaded\" \/>\n<meta property=\"og:url\" content=\"https:\/\/argentinareloaded.com\/eng\/sao-paulo-brazil\/\" \/>\n<meta property=\"og:site_name\" content=\"Argentina Reloaded\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-08T15:57:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-28T16:51:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/sao_paulo_argentina_reloaded-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Flor I\u00f1igo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Flor I\u00f1igo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/\"},\"author\":{\"name\":\"Flor I\u00f1igo\",\"@id\":\"https:\/\/argentinareloaded.com\/#\/schema\/person\/9c720160da73e0de4b294a87d17ab14e\"},\"headline\":\"SAO PAULO, Brazil\",\"datePublished\":\"2022-12-08T15:57:30+00:00\",\"dateModified\":\"2025-04-28T16:51:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/\"},\"wordCount\":839,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/argentinareloaded.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/sao_paulo_argentina_reloaded-scaled.jpg\",\"articleSection\":[\"agenda old\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/\",\"url\":\"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/\",\"name\":\"SAO PAULO, Brazil - Argentina Reloaded\",\"isPartOf\":{\"@id\":\"https:\/\/argentinareloaded.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/sao_paulo_argentina_reloaded-scaled.jpg\",\"datePublished\":\"2022-12-08T15:57:30+00:00\",\"dateModified\":\"2025-04-28T16:51:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/#primaryimage\",\"url\":\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/sao_paulo_argentina_reloaded-scaled.jpg\",\"contentUrl\":\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/sao_paulo_argentina_reloaded-scaled.jpg\",\"width\":2560,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/argentinareloaded.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SAO PAULO, Brazil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/argentinareloaded.com\/#website\",\"url\":\"https:\/\/argentinareloaded.com\/\",\"name\":\"STUDIO COURTOIS\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/argentinareloaded.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/argentinareloaded.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/argentinareloaded.com\/#organization\",\"name\":\"Studio Courtois\",\"url\":\"https:\/\/argentinareloaded.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/argentinareloaded.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2020\/10\/HOME-2-scaled.jpg\",\"contentUrl\":\"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2020\/10\/HOME-2-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Studio Courtois\"},\"image\":{\"@id\":\"https:\/\/argentinareloaded.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.instagram.com\/studiocourtois\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/argentinareloaded.com\/#\/schema\/person\/9c720160da73e0de4b294a87d17ab14e\",\"name\":\"Flor I\u00f1igo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/argentinareloaded.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c71ded7c4cb41bfedd8f96f9aaaa2352bde3c6a49d1d1851eab772aa7e6585c8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c71ded7c4cb41bfedd8f96f9aaaa2352bde3c6a49d1d1851eab772aa7e6585c8?s=96&d=mm&r=g\",\"caption\":\"Flor I\u00f1igo\"},\"sameAs\":[\"https:\/\/argentinareloaded.com\/\"],\"url\":\"https:\/\/argentinareloaded.com\/eng\/author\/flor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SAO PAULO, Brazil - Argentina Reloaded","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/argentinareloaded.com\/eng\/sao-paulo-brazil\/","og_locale":"en_GB","og_type":"article","og_title":"SAO PAULO, Brazil - Argentina Reloaded","og_url":"https:\/\/argentinareloaded.com\/eng\/sao-paulo-brazil\/","og_site_name":"Argentina Reloaded","article_published_time":"2022-12-08T15:57:30+00:00","article_modified_time":"2025-04-28T16:51:22+00:00","og_image":[{"width":2560,"height":2560,"url":"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/sao_paulo_argentina_reloaded-scaled.jpg","type":"image\/jpeg"}],"author":"Flor I\u00f1igo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Flor I\u00f1igo","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/#article","isPartOf":{"@id":"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/"},"author":{"name":"Flor I\u00f1igo","@id":"https:\/\/argentinareloaded.com\/#\/schema\/person\/9c720160da73e0de4b294a87d17ab14e"},"headline":"SAO PAULO, Brazil","datePublished":"2022-12-08T15:57:30+00:00","dateModified":"2025-04-28T16:51:22+00:00","mainEntityOfPage":{"@id":"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/"},"wordCount":839,"commentCount":0,"publisher":{"@id":"https:\/\/argentinareloaded.com\/#organization"},"image":{"@id":"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/#primaryimage"},"thumbnailUrl":"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/sao_paulo_argentina_reloaded-scaled.jpg","articleSection":["agenda old"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/argentinareloaded.com\/sao-paulo-brazil\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/","url":"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/","name":"SAO PAULO, Brazil - Argentina Reloaded","isPartOf":{"@id":"https:\/\/argentinareloaded.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/#primaryimage"},"image":{"@id":"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/#primaryimage"},"thumbnailUrl":"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/sao_paulo_argentina_reloaded-scaled.jpg","datePublished":"2022-12-08T15:57:30+00:00","dateModified":"2025-04-28T16:51:22+00:00","breadcrumb":{"@id":"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/argentinareloaded.com\/sao-paulo-brazil\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/#primaryimage","url":"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/sao_paulo_argentina_reloaded-scaled.jpg","contentUrl":"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2022\/10\/sao_paulo_argentina_reloaded-scaled.jpg","width":2560,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/argentinareloaded.com\/sao-paulo-brazil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/argentinareloaded.com\/"},{"@type":"ListItem","position":2,"name":"SAO PAULO, Brazil"}]},{"@type":"WebSite","@id":"https:\/\/argentinareloaded.com\/#website","url":"https:\/\/argentinareloaded.com\/","name":"STUDIO COURTOIS","description":"","publisher":{"@id":"https:\/\/argentinareloaded.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/argentinareloaded.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/argentinareloaded.com\/#organization","name":"Studio Courtois","url":"https:\/\/argentinareloaded.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/argentinareloaded.com\/#\/schema\/logo\/image\/","url":"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2020\/10\/HOME-2-scaled.jpg","contentUrl":"https:\/\/argentinareloaded.com\/wp-content\/uploads\/2020\/10\/HOME-2-scaled.jpg","width":2560,"height":1707,"caption":"Studio Courtois"},"image":{"@id":"https:\/\/argentinareloaded.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/studiocourtois\/"]},{"@type":"Person","@id":"https:\/\/argentinareloaded.com\/#\/schema\/person\/9c720160da73e0de4b294a87d17ab14e","name":"Flor I\u00f1igo","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/argentinareloaded.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c71ded7c4cb41bfedd8f96f9aaaa2352bde3c6a49d1d1851eab772aa7e6585c8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c71ded7c4cb41bfedd8f96f9aaaa2352bde3c6a49d1d1851eab772aa7e6585c8?s=96&d=mm&r=g","caption":"Flor I\u00f1igo"},"sameAs":["https:\/\/argentinareloaded.com\/"],"url":"https:\/\/argentinareloaded.com\/eng\/author\/flor\/"}]}},"_links":{"self":[{"href":"https:\/\/argentinareloaded.com\/eng\/wp-json\/wp\/v2\/posts\/52808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/argentinareloaded.com\/eng\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/argentinareloaded.com\/eng\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/argentinareloaded.com\/eng\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/argentinareloaded.com\/eng\/wp-json\/wp\/v2\/comments?post=52808"}],"version-history":[{"count":1,"href":"https:\/\/argentinareloaded.com\/eng\/wp-json\/wp\/v2\/posts\/52808\/revisions"}],"predecessor-version":[{"id":55518,"href":"https:\/\/argentinareloaded.com\/eng\/wp-json\/wp\/v2\/posts\/52808\/revisions\/55518"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/argentinareloaded.com\/eng\/wp-json\/wp\/v2\/media\/52444"}],"wp:attachment":[{"href":"https:\/\/argentinareloaded.com\/eng\/wp-json\/wp\/v2\/media?parent=52808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/argentinareloaded.com\/eng\/wp-json\/wp\/v2\/categories?post=52808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/argentinareloaded.com\/eng\/wp-json\/wp\/v2\/tags?post=52808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}